{"id":1946,"date":"2026-03-31T19:04:11","date_gmt":"2026-03-31T19:04:11","guid":{"rendered":"https:\/\/studenthub.elsevier.com\/de\/?p=1946"},"modified":"2026-04-15T12:42:49","modified_gmt":"2026-04-15T12:42:49","slug":"hyperglykamie","status":"publish","type":"post","link":"https:\/\/studenthub.elsevier.com\/de\/pflegeplanung\/hyperglykamie\/","title":{"rendered":"Hyperglyk\u00e4mie"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">\nErh\u00f6hter Blutzuckerspiegel im Blut; syn. Blutzuckererh\u00f6hung; weiterf\u00fchrende Stichworte: Adipositas\/\u00dcbergewicht, Bauchschmerzen\/Abdominalschmerzen,Bewusstseinsver\u00e4nderung\/Vigilanzst\u00f6rung, Diabetes mellitus\/Zuckerkrankheit, Erbrechen\/Emesis, Hypercholesterin\u00e4mie, Schwindel\/Vertigo,Sturzgefahr, \u00dcbelkeit\/Nausea<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Informationen sammeln<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">\u25b7 Screening zur Ermittlung des Blutzuckerspiegels<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Wie und seit wann zeigt sich die Hyperglyk\u00e4mie?<\/li>\n\n\n\n<li>Ist Diabetes bekannt?<\/li>\n\n\n\n<li>Diabetisches Koma?<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">Ursachen<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Diabetes mellitus? Welche Form?<\/li>\n\n\n\n<li>Therapie mit Cortison?<\/li>\n\n\n\n<li>Akuter Stress\/Trauma\/Sturz?<\/li>\n\n\n\n<li>Infekte?<\/li>\n\n\n\n<li>Alkoholkonsum?<\/li>\n\n\n\n<li>Dosierungsfehler von Insulin-Injektion?<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">Symptome<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Wie hoch ist der Blutzucker?<\/li>\n\n\n\n<li>Begleitsymptome?<br>\u2013 Starker Durst (Polydipsie)?<br>\u2013 Urinmenge?<br>\u2013 Polyurie?<br>\u2013 Oligurie\/Anurie?<br>\u2013 Urinfarbe?<br>\u2013 Dehydratation?<br>\u2013 Appetitlosigkeit?<br>\u2013 \u00dcbelkeit?<br>\u2013 Erbrechen?<br>\u2013 Bauchschmerzen?<br>\u2013 Schw\u00e4che?<br>\u2013 Haut? Trocken, hei\u00df?<br>\u2013 Ku\u00dfmaul-Atmung?<br>\u2013 Azetongeruch der Atmung?<br>\u2013 Schlaffe Muskulatur?<br>\u2013 Kr\u00e4mpfe?<br>\u2013 Bewusstseinszustand?<\/li>\n\n\n\n<li>Orientierung?<\/li>\n\n\n\n<li>Pulsfrequenz? Tachykardie?<\/li>\n\n\n\n<li>Blutdruck? Hypotonie?<\/li>\n\n\n\n<li>Verlangsamte Reflexe?<\/li>\n\n\n\n<li>Hypotone Muskulatur?<\/li>\n\n\n\n<li>Schock?<\/li>\n\n\n\n<li>Bewusstseinsst\u00f6rung?<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">Ressourcen<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Pat. kennt Ursache der Hyperglyk\u00e4mie<\/li>\n\n\n\n<li>Pat. kann BZ-Werte selbst kontrollieren<\/li>\n\n\n\n<li>Pat. kann selbst Insulin spritzen<\/li>\n\n\n\n<li>Pat. f\u00fchrt ein Diabetikertagebuch<\/li>\n\n\n\n<li>Pat. ist orientiert<\/li>\n\n\n\n<li>Guter AZ des Pat.<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">Ziele festlegen<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Blutzuckerspiegel des Pat. wird konstantangsam gesenkt max. 50 mg\/dl in einer Stunde bei BZ-Werten von &lt;250 mg\/dl<\/li>\n\n\n\n<li>Pat. hat einen Blutzuckerspiegel im Normbereich (HbA1c &lt; 7)<\/li>\n\n\n\n<li>Pat. kennt M\u00f6glichkeiten der Stoffwechselselbstkontrolle und wendet diese selbstst\u00e4ndig an (BZ-Kontrolle, Diabetiker-Tagebuch, etc.)<\/li>\n\n\n\n<li>Pat. kennt die Blutzuckerwirksamkeit der Nahrungsmittel und passt seine Ern\u00e4hrung an den Blutzuckerspiegel an<\/li>\n\n\n\n<li>Pat. kennt die Therapie und kann eigenst\u00e4ndig Korrekturen der Behandlung vornehmen<\/li>\n\n\n\n<li>Pat. setzt blutzuckersenkende Medikamente regelm\u00e4\u00dfig und kontrolliert ein<\/li>\n\n\n\n<li>Pat. kennt den Einfluss von k\u00f6rperlicher Bewegung auf den Blutzuckerspiegel und kann eigenst\u00e4ndig Anpassungen vornehmen<\/li>\n\n\n\n<li>Pat. kennt Fr\u00fchzeichen einer Hyperglyk\u00e4mie<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">Ma\u00dfnahmen planen<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Bei Bewusstseinsst\u00f6rung Notfallma\u00dfnahmen<\/li>\n\n\n\n<li>Aspirationsprophylaxe<\/li>\n\n\n\n<li>Vermehrte Vitalzeichenkontrolle<\/li>\n\n\n\n<li>Ggf. alle notwendigen Prophylaxen<\/li>\n\n\n\n<li>Vermehrte BZ-Kontrollen (oft st\u00fcndlich)<\/li>\n\n\n\n<li>Ggf. Fl\u00fcssigkeitsbilanzierung<\/li>\n\n\n\n<li>Beratung\/Schulung des Pat. und ggf. seiner<br>Angeh\u00f6rigen (Diabetesschulung):<br>\u2013 Ursachen und Verlauf der Erkrankung<br>\u2013 Komplikationen<br>\u2013 Medikament\u00f6se Therapie<br>\u2013 Blutzuckertagebuch<br>\u2013 Ern\u00e4hrungsberatung<br>\u2013 Haut- und Fu\u00dfpflege<br>\u2013 Notfallma\u00dfnahmen<br>\u2013 Bewegung<\/li>\n\n\n\n<li>Anleitung zur\/zum:<br>\u2013 Blutzuckerermittlung durch einen<br>Glukosesensor<br>\u2013 Blutzuckerschnelltest<br>\u2013 Richtigen Gebrauch von Insulin und entsprechenden<br>Applikationshilfen<\/li>\n\n\n\n<li>Vermehrt Getr\u00e4nke anbieten<\/li>\n\n\n\n<li>Angeh\u00f6rige und Umfeld, z. B. Schule, in Notfallma\u00dfnahmen einweisen<\/li>\n\n\n\n<li>Kontakt zu Selbsthilfegruppen herstellen<\/li>\n\n\n\n<li>Ggf. Neueinstellung der Medikamenten<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">Ergebnisse pr\u00fcfen<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Laborwerte<\/li>\n\n\n\n<li>Fl\u00fcssigkeitsbilanzierung<\/li>\n\n\n\n<li>Vitalzeichen<\/li>\n\n\n\n<li>Bewusstseinslage<\/li>\n\n\n\n<li>Krankheitsverst\u00e4ndnis, Compliance<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Erh\u00f6hter Blutzuckerspiegel im Blut; syn. Blutzuckererh\u00f6hung; weiterf\u00fchrende Stichworte: Adipositas\/\u00dcbergewicht, Bauchschmerzen\/Abdominalschmerzen,Bewusstseinsver\u00e4nderung\/Vigilanzst\u00f6rung, Diabetes mellitus\/Zuckerkrankheit, Erbrechen\/Emesis, Hypercholesterin\u00e4mie, Schwindel\/Vertigo,Sturzgefahr, \u00dcbelkeit\/Nausea<\/p>\n","protected":false},"author":172,"featured_media":2165,"comment_status":"open","ping_status":"open","sticky":false,"template":"pflegenplanung-individual-entry","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[28],"tags":[],"class_list":["post-1946","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-pflegeplanung"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Hyperglyk\u00e4mie - Student Hub Germany<\/title>\n<meta name=\"description\" content=\"Hyperglyk\u00e4mie: Ursachen, Symptome, Diagnostik und Behandlung. Wichtiges Wissen f\u00fcr Diabetespatienten und die Pr\u00e4vention von Komplikationen.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/studenthub.elsevier.com\/de\/pflegeplanung\/hyperglykamie\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Hyperglyk\u00e4mie - Student Hub Germany\" \/>\n<meta property=\"og:description\" content=\"Hyperglyk\u00e4mie: Ursachen, Symptome, Diagnostik und Behandlung. Wichtiges Wissen f\u00fcr Diabetespatienten und die Pr\u00e4vention von Komplikationen.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/studenthub.elsevier.com\/de\/pflegeplanung\/hyperglykamie\/\" \/>\n<meta property=\"og:site_name\" content=\"Student Hub Germany\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-31T19:04:11+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-15T12:42:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/studenthub.elsevier.com\/de\/wp-content\/uploads\/sites\/14\/2026\/03\/33.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"627\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"smatiasek\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"smatiasek\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/studenthub.elsevier.com\/de\/pflegeplanung\/hyperglykamie\/\",\"url\":\"https:\/\/studenthub.elsevier.com\/de\/pflegeplanung\/hyperglykamie\/\",\"name\":\"Hyperglyk\u00e4mie - Student Hub Germany\",\"isPartOf\":{\"@id\":\"https:\/\/studenthub.elsevier.com\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/studenthub.elsevier.com\/de\/pflegeplanung\/hyperglykamie\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/studenthub.elsevier.com\/de\/pflegeplanung\/hyperglykamie\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/studenthub.elsevier.com\/de\/wp-content\/uploads\/sites\/14\/2026\/03\/33.jpg\",\"datePublished\":\"2026-03-31T19:04:11+00:00\",\"dateModified\":\"2026-04-15T12:42:49+00:00\",\"author\":{\"@id\":\"https:\/\/studenthub.elsevier.com\/de\/#\/schema\/person\/a44a09d322f13e112d71e4b2378c2d3f\"},\"description\":\"Hyperglyk\u00e4mie: Ursachen, Symptome, Diagnostik und Behandlung. Wichtiges Wissen f\u00fcr Diabetespatienten und die Pr\u00e4vention von Komplikationen.\",\"breadcrumb\":{\"@id\":\"https:\/\/studenthub.elsevier.com\/de\/pflegeplanung\/hyperglykamie\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/studenthub.elsevier.com\/de\/pflegeplanung\/hyperglykamie\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/studenthub.elsevier.com\/de\/pflegeplanung\/hyperglykamie\/#primaryimage\",\"url\":\"https:\/\/studenthub.elsevier.com\/de\/wp-content\/uploads\/sites\/14\/2026\/03\/33.jpg\",\"contentUrl\":\"https:\/\/studenthub.elsevier.com\/de\/wp-content\/uploads\/sites\/14\/2026\/03\/33.jpg\",\"width\":1200,\"height\":627},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/studenthub.elsevier.com\/de\/pflegeplanung\/hyperglykamie\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/studenthub.elsevier.com\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Hyperglyk\u00e4mie\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/studenthub.elsevier.com\/de\/#website\",\"url\":\"https:\/\/studenthub.elsevier.com\/de\/\",\"name\":\"Student Hub Germany\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/studenthub.elsevier.com\/de\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/studenthub.elsevier.com\/de\/#\/schema\/person\/a44a09d322f13e112d71e4b2378c2d3f\",\"name\":\"smatiasek\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/studenthub.elsevier.com\/de\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c346af4be615dd5eac96b3525a1af55dfcdaa88ee27c3d8b6b3c5bf6ba78c57d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c346af4be615dd5eac96b3525a1af55dfcdaa88ee27c3d8b6b3c5bf6ba78c57d?s=96&d=mm&r=g\",\"caption\":\"smatiasek\"},\"url\":\"https:\/\/studenthub.elsevier.com\/de\/author\/smatiasek\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Hyperglyk\u00e4mie - Student Hub Germany","description":"Hyperglyk\u00e4mie: Ursachen, Symptome, Diagnostik und Behandlung. Wichtiges Wissen f\u00fcr Diabetespatienten und die Pr\u00e4vention von Komplikationen.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/studenthub.elsevier.com\/de\/pflegeplanung\/hyperglykamie\/","og_locale":"de_DE","og_type":"article","og_title":"Hyperglyk\u00e4mie - Student Hub Germany","og_description":"Hyperglyk\u00e4mie: Ursachen, Symptome, Diagnostik und Behandlung. Wichtiges Wissen f\u00fcr Diabetespatienten und die Pr\u00e4vention von Komplikationen.","og_url":"https:\/\/studenthub.elsevier.com\/de\/pflegeplanung\/hyperglykamie\/","og_site_name":"Student Hub Germany","article_published_time":"2026-03-31T19:04:11+00:00","article_modified_time":"2026-04-15T12:42:49+00:00","og_image":[{"width":1200,"height":627,"url":"https:\/\/studenthub.elsevier.com\/de\/wp-content\/uploads\/sites\/14\/2026\/03\/33.jpg","type":"image\/jpeg"}],"author":"smatiasek","twitter_card":"summary_large_image","twitter_misc":{"Written by":"smatiasek","Est. reading time":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/studenthub.elsevier.com\/de\/pflegeplanung\/hyperglykamie\/","url":"https:\/\/studenthub.elsevier.com\/de\/pflegeplanung\/hyperglykamie\/","name":"Hyperglyk\u00e4mie - Student Hub Germany","isPartOf":{"@id":"https:\/\/studenthub.elsevier.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/studenthub.elsevier.com\/de\/pflegeplanung\/hyperglykamie\/#primaryimage"},"image":{"@id":"https:\/\/studenthub.elsevier.com\/de\/pflegeplanung\/hyperglykamie\/#primaryimage"},"thumbnailUrl":"https:\/\/studenthub.elsevier.com\/de\/wp-content\/uploads\/sites\/14\/2026\/03\/33.jpg","datePublished":"2026-03-31T19:04:11+00:00","dateModified":"2026-04-15T12:42:49+00:00","author":{"@id":"https:\/\/studenthub.elsevier.com\/de\/#\/schema\/person\/a44a09d322f13e112d71e4b2378c2d3f"},"description":"Hyperglyk\u00e4mie: Ursachen, Symptome, Diagnostik und Behandlung. Wichtiges Wissen f\u00fcr Diabetespatienten und die Pr\u00e4vention von Komplikationen.","breadcrumb":{"@id":"https:\/\/studenthub.elsevier.com\/de\/pflegeplanung\/hyperglykamie\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/studenthub.elsevier.com\/de\/pflegeplanung\/hyperglykamie\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/studenthub.elsevier.com\/de\/pflegeplanung\/hyperglykamie\/#primaryimage","url":"https:\/\/studenthub.elsevier.com\/de\/wp-content\/uploads\/sites\/14\/2026\/03\/33.jpg","contentUrl":"https:\/\/studenthub.elsevier.com\/de\/wp-content\/uploads\/sites\/14\/2026\/03\/33.jpg","width":1200,"height":627},{"@type":"BreadcrumbList","@id":"https:\/\/studenthub.elsevier.com\/de\/pflegeplanung\/hyperglykamie\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/studenthub.elsevier.com\/de\/"},{"@type":"ListItem","position":2,"name":"Hyperglyk\u00e4mie"}]},{"@type":"WebSite","@id":"https:\/\/studenthub.elsevier.com\/de\/#website","url":"https:\/\/studenthub.elsevier.com\/de\/","name":"Student Hub Germany","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/studenthub.elsevier.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/studenthub.elsevier.com\/de\/#\/schema\/person\/a44a09d322f13e112d71e4b2378c2d3f","name":"smatiasek","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/studenthub.elsevier.com\/de\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c346af4be615dd5eac96b3525a1af55dfcdaa88ee27c3d8b6b3c5bf6ba78c57d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c346af4be615dd5eac96b3525a1af55dfcdaa88ee27c3d8b6b3c5bf6ba78c57d?s=96&d=mm&r=g","caption":"smatiasek"},"url":"https:\/\/studenthub.elsevier.com\/de\/author\/smatiasek\/"}]}},"jetpack_featured_media_url":"https:\/\/studenthub.elsevier.com\/de\/wp-content\/uploads\/sites\/14\/2026\/03\/33.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/studenthub.elsevier.com\/de\/wp-json\/wp\/v2\/posts\/1946","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/studenthub.elsevier.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/studenthub.elsevier.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/studenthub.elsevier.com\/de\/wp-json\/wp\/v2\/users\/172"}],"replies":[{"embeddable":true,"href":"https:\/\/studenthub.elsevier.com\/de\/wp-json\/wp\/v2\/comments?post=1946"}],"version-history":[{"count":5,"href":"https:\/\/studenthub.elsevier.com\/de\/wp-json\/wp\/v2\/posts\/1946\/revisions"}],"predecessor-version":[{"id":2224,"href":"https:\/\/studenthub.elsevier.com\/de\/wp-json\/wp\/v2\/posts\/1946\/revisions\/2224"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/studenthub.elsevier.com\/de\/wp-json\/wp\/v2\/media\/2165"}],"wp:attachment":[{"href":"https:\/\/studenthub.elsevier.com\/de\/wp-json\/wp\/v2\/media?parent=1946"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/studenthub.elsevier.com\/de\/wp-json\/wp\/v2\/categories?post=1946"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/studenthub.elsevier.com\/de\/wp-json\/wp\/v2\/tags?post=1946"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}